{"id":38968,"date":"2026-01-27T11:58:55","date_gmt":"2026-01-27T11:58:55","guid":{"rendered":"https:\/\/hughes1stg.wpenginepowered.com\/soluciones\/servicios-satelitales-systems-terrestre\/servicios-satelitales-systems-terrestre-antena-electronicamente-orientable"},"modified":"2026-03-24T19:14:20","modified_gmt":"2026-03-24T19:14:20","slug":"servicios-satelitales-systems-terrestre-antena-electronicamente-orientable","status":"publish","type":"page","link":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable","title":{"rendered":"Antena Electr\u00f3nicamente Orientable de Hughes (ESA) para Baja \u00d3rbita Terrestre (LEO)"},"content":{"rendered":"<!-- Solution Hero --><section class=\"solution-hero-section\">\r\n    <div class=\"shs-wrapper bg-dark border-radius-bottom-lr\">\r\n        <div class=\"shs-hero\"><div class=\"shs-bg-media\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120W-Hero_0.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120W-Hero_0.webp 1280w, https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120W-Hero_0-300x113.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120W-Hero_0-1024x384.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120W-Hero_0-768x288.webp 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" alt=\"HL1120W\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1280\" height=\"480\" fetchpriority=\"high\"><\/div><div class=\"container\">\r\n                <div class=\"shs-hero-content\"><h1 class=\"h1 title\">Antena Electr\u00f3nicamente Orientable de Hughes (ESA) para Baja \u00d3rbita Terrestre (LEO)<\/h1><h2 class=\"desc\"><p>Antena de Panel Plano para Sat\u00e9lites LEO de OneWeb<\/p>\n<\/h2><\/div>\r\n            <\/div><\/div><div class=\"shs-overview\">\r\n                <div class=\"container\">\r\n                    <div class=\"shs-overview-content row\"><div class=\"introduction -lg cell-12\"><p>La antena de panel plano y electr\u00f3nicamente orientable de Hughes (ESA, por sus siglas en ingl\u00e9s) es la \u00faltima innovaci\u00f3n disponible para los clientes de Hughes y los socios distribuidores de OneWeb, ofreciendo conectividad global de alto rendimiento y baja latencia.<\/p>\n<p>Los terminales de Hughes incluyen una antena de perfil delgado con panel plano y m\u00f3dem integrado. Estos dispositivos son livianos, de bajo consumo, resistentes a la intemperie y f\u00e1ciles de instalar y mantener.<\/p>\n<p>Hughes proporciona la experiencia tecnol\u00f3gica detr\u00e1s de la electr\u00f3nica de las estaciones terrestres de OneWeb y los m\u00f3dulos centrales, lo que nos da una ventaja en la ingenier\u00eda e integraci\u00f3n de los terminales ESA. Con m\u00e1s de diez millones de terminales satelitales fabricados, el equipo de Hughes es experto en dise\u00f1ar y construir soluciones de terminales para conectividad satelital.<\/p>\n<\/div><div class=\"left-column -lg cell-md-6\"><p><br data-mce-bogus=\"1\"><\/p>\n<\/div><div class=\"right-column -lg cell-md-6\"><p><br data-mce-bogus=\"1\"><\/p>\n<\/div><\/div>\r\n                <\/div>\r\n            <\/div><\/div>\r\n<\/section>\n\n<!-- Text Block --><section class=\"wysiwyg-component space-md-m\">\n        <div class=\"container\">\n            <div class=\"wc-wrap\"><div class=\"wc-decs bullet-styled\"><h2>Terminales livianos y de Alto Desempe\u00f1o<\/h2>\n<\/div><\/div>\n        <\/div>\n    <\/section>\n\n<!-- Two-Column Content --><section class=\"two-column-content-section space-lg-m\">\r\n        <div class=\"container\"><div class=\"tccs-row row\"><div class=\"tccs-row-left cell-md-6\"><div class=\"tccs-text-block bullet-styled\"><h3 class=\"text-align-center\" style=\"text-align: left;\">HL1100W<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30378\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1100W-product.png.webp\" alt=\"1100 Product \" width=\"570\" height=\"230\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1100W-product.png.webp 570w, https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1100W-product.png-300x121.webp 300w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/p>\n<\/div><div class=\"btn-wrap\"><a class=\"btn\" href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/Hughes_LEO_HL1100W_Terminal-datasheet.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Datasheet HL1100W\" >Datasheet HL1100W<\/a><\/div><\/div><div class=\"tccs-row-right cell-md-6\"><div class=\"tccs-text-block bullet-styled\"><h3 class=\"text-align-center\" style=\"text-align: left;\">HL1120W<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-30398\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120W-back-transparent.png.webp\" alt=\"Back of HL1120W\" width=\"570\" height=\"230\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120W-back-transparent.png.webp 570w, https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120W-back-transparent.png-300x121.webp 300w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/p>\n<\/div><div class=\"btn-wrap\"><a class=\"btn\" href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/Hughes_LEO_HL1120W_Terminal.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Datasheet HL1120W\" >Datasheet HL1120W<\/a><\/div><\/div><\/div><\/div>\r\n    <\/section>\n\n<!-- Full-Width CTA --><section class=\"full-width-cta-section border-radius-top-lr left bg-gradient\">\r\n        <div class=\"container\">\r\n            <div class=\"fwc-row row align-items-center\"><div class=\"fwc-left cell-md-7\">\r\n                        <div class=\"fwc-content\"><h2 class=\"fwc-title\">Interesado en Comprar Equipos<\/h2><div class=\"desc\"><p>El portal de compra est\u00e1 disponible para socios distribuidores de OneWeb y clientes de Hughes<\/p>\n<\/div><\/div><\/div><div class=\"fwc-right cell-md-5\"><div class=\"btn-wrap text-left text-md-right\"><a class=\"btn -secondary\" href=\"https:\/\/hughesesa.motorbrain.com\/\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Comprar ahora\" >Comprar ahora<\/a><\/div><\/div><\/div>\r\n        <\/div>\r\n    <\/section>\n\n<!-- Text Block --><section class=\"wysiwyg-component space-md-m\">\n        <div class=\"container\">\n            <div class=\"wc-wrap\"><div class=\"wc-decs bullet-styled\"><table>\n<tbody>\n<tr>\n<td><\/td>\n<td><strong>Terminal LEO de Hughes (HL1100) Panel Sencillo<\/strong><\/td>\n<td><strong>Terminal LEO de Hughes (HL1120) Doble Panel<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"200\"><strong>Velocidad M\u00e1xima de Descarga<\/strong><\/td>\n<td width=\"293\">hasta 75 Mbps<\/td>\n<td width=\"292\">hasta 195 Mbps<\/td>\n<\/tr>\n<tr>\n<td width=\"200\"><strong>Velocidad M\u00e1xima de Subida<\/strong><\/td>\n<td width=\"293\">hasta 14 Mbps<\/td>\n<td width=\"292\">hasta 32 Mbps<\/td>\n<\/tr>\n<tr>\n<td width=\"200\"><strong>Dimensiones<\/strong><\/td>\n<td width=\"293\">23.5 in. x 15.8 in x 2.4 in<\/td>\n<td width=\"292\">23.5 in. \u00d7 32.6 in. \u00d7 5.4 in.<\/td>\n<\/tr>\n<tr>\n<td width=\"200\"><strong>Peso<\/strong><\/td>\n<td width=\"293\">23.34 lb. (10.59 kg)<\/td>\n<td width=\"292\">53.2 lbs. (24.13kg)<\/td>\n<\/tr>\n<tr>\n<td width=\"200\"><strong>Temperatura de Funcionamiento<\/strong><\/td>\n<td width=\"293\">-40\u00b0C to + 55\u00b0C<\/td>\n<td width=\"292\">-40\u00b0C to + 55\u00b0C<\/td>\n<\/tr>\n<tr>\n<td width=\"200\"><strong>Clasificaci\u00f3n Ambiental<\/strong><\/td>\n<td width=\"293\">IP67<\/td>\n<td width=\"292\">IP67<\/td>\n<\/tr>\n<tr>\n<td width=\"200\"><strong>Wi-Fi 6\u00a0<\/strong><\/td>\n<td width=\"293\">Incluido<\/td>\n<td width=\"292\">Incluido<\/td>\n<\/tr>\n<tr>\n<td width=\"200\"><strong>Puerto RJ45 GigE<\/strong><\/td>\n<td width=\"293\">2 incluidos<\/td>\n<td width=\"292\">2 incluidos<\/td>\n<\/tr>\n<tr>\n<td width=\"200\"><strong>Temperatura de Supervivencia<\/strong><\/td>\n<td width=\"293\">-50\u00b0C to +85\u00b0C<\/td>\n<td width=\"292\">-50\u00b0C to +85\u00b0C<\/td>\n<\/tr>\n<tr>\n<td width=\"200\"><strong>Consumo Energ\u00e9tico (Promedio)<\/strong><\/td>\n<td width=\"293\">130W<\/td>\n<td width=\"292\">300W<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><\/div>\n        <\/div>\n    <\/section>\n\n<!-- Two-Column Content --><section class=\"two-column-content-section space-lg-m\">\r\n        <div class=\"container\"><div class=\"tccs-row row\"><div class=\"tccs-row-left cell-lg-5 cell-md-6\"><div class=\"tccs-video-block\"><a href=\"https:\/\/youtu.be\/p_hTUpeyH1o?si=ye1tXQ6H0aYiNQ7b\" class=\"inline-media tccs-media\" data-fancybox  aria-label=\"Play video\"><img sizes=\"(max-width: 1280px) 100vw, 1280px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Oayomn-8wrc-300x169.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Oayomn-8wrc-1024x576.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Oayomn-8wrc-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Oayomn-8wrc-768x432.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Oayomn-8wrc.webp 1280w\" decoding=\"async\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Oayomn-8wrc.webp\" alt=\"Antena Electr\u00f3nicamente Orientable de Hughes (ESA) para Baja \u00d3rbita Terrestre (LEO) Image\" class=\"\" loading=\"lazy\" width=\"1280\" height=\"720\"><i class=\"btn-play\"><\/i><\/a><\/div><\/div><div class=\"tccs-row-right cell-lg-7 cell-md-6\"><div class=\"tccs-text-block bullet-styled\"><h2>Tecnolog\u00eda Innovadora para Antenas de Panel Plano<\/h2>\n<p>La antena ESA de Hughes permite transiciones fluidas entre beams satelitales para mantener una conectividad ininterrumpida.<\/p>\n<p>Mira el video para saber m\u00e1s.<\/p>\n<\/div><\/div><\/div><\/div>\r\n    <\/section>\n\n<!-- Promo Media --><section class=\"promo-media-section space-sm-m bg-gradient-blue-bottom border-radius-bottom-lr\">\r\n    <div class=\"container\">\r\n        <div class=\"pms-row row align-items-center\"><div class=\"pms-left cell-md-6\">\r\n                    <div class=\"pms-content\"><h2 class=\"h2\">  Hughes es la opci\u00f3n ideal para los terminales satelitales LEO de OneWeb.<\/h2><\/div>\r\n                <\/div><div class=\"pms-right cell-md-6\"><div class=\"pms-media\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/CellOnWheels.jpg.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/CellOnWheels.jpg.webp 1440w, https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/CellOnWheels.jpg-300x169.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/CellOnWheels.jpg-1024x576.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/CellOnWheels.jpg-768x432.webp 768w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" alt=\" Low-angle shot of a portable communication base station featuring a modern dual-panel antenna\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"810\"><\/div><\/div><\/div>\r\n    <\/div>\r\n<\/section>\n\n<!-- Two-Column Content --><section class=\"two-column-content-section space-lg-m\">\r\n        <div class=\"container\"><div class=\"tccs-row row\"><div class=\"tccs-row-left cell-md-6\"><div class=\"tccs-image-block\">\r\n                                        <div class=\"tccs-image\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/GettyImages-1182564576_730x462px.jpg.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/GettyImages-1182564576_730x462px.jpg.webp 730w, https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/GettyImages-1182564576_730x462px.jpg-300x190.webp 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" alt=\"Person holding phone with Hughes LEO App\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"462\"><\/div>\r\n                                    <\/div><\/div><div class=\"tccs-row-right cell-md-6\"><div class=\"tccs-text-block bullet-styled\"><h2>Aplicaci\u00f3n LEO de Hughes<\/h2>\n<p>El terminal LEO de Hughes se configura y activa mediante la aplicaci\u00f3n LEO. Esta aplicaci\u00f3n proporciona acceso r\u00e1pido a la configuraci\u00f3n para instaladores y usuarios finales.<\/p>\n<\/div><div class=\"btn-wrap\"><a class=\"btn\" href=\"https:\/\/www.hughes.com\/resources\/supplier-technical-support\/leo-app\" target=\"_self\" rel=\"nofollow\" aria-label=\"Descarga Ahora\" >Descarga Ahora<\/a><\/div><div class=\"btn-wrap\"><a class=\"btn\" href=\"https:\/\/www.hughes.com\/resources\/insights\/leo-satellites\/hughes-simplifies-esa-installation-and-maintenance-new-leo-mobile\" target=\"_self\" rel=\"nofollow\" aria-label=\"Lee el Blog \" >Lee el Blog <\/a><\/div><\/div><\/div><\/div>\r\n    <\/section>\n\n<!-- Expandable Listing --><section class=\"expandable-listing-section space-lg-m\">\r\n        <div class=\"container\"><div class=\"els-list accordion-list\"><div class=\"els-item accordion-item\"><div class=\"els-title accordion-title has-content\">\r\n                                    <span>Datasheets<\/span><i class=\"icon\"><svg aria-hidden=\"true\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"currentColor\"><use xlink:href=\"#icon-btn-arrow\"><\/use><\/svg><\/i><\/div><div class=\"els-content accordion-content\"><div class=\"els-desc\"><ul>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/Hughes_LEO_HL1100W_Terminal-datasheet.pdf\" target=\"_blank\" rel=\"noopener\">Terminal LEO HL 1100W de Hughes<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/Hughes_LEO_HL1120W_Terminal.pdf\" target=\"_blank\" rel=\"noopener\">Terminal LEO HL 1200W de Hughes<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/Hughes-LEO-HL1100W-Fixed-Mount-Options.pdf\" target=\"_blank\" rel=\"noopener\">Opciones de Montaje Fijo HL1100<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/Hughes-LEO-HL1120W-Fixed-Mount-Options.pdf\" target=\"_blank\" rel=\"noopener\">Opciones de Montaje Fijo HL1200<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1100-Mobility-Mounts.pdf\" target=\"_blank\" rel=\"noopener\">Opciones de Montaje M\u00f3vil HL1100<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120-Mobility-Mounts.pdf\" target=\"_blank\" rel=\"noopener\">Opciones de Montaje M\u00f3vil HL1200<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1100W-Transportable-Pop-Up-Case.pdf\" target=\"_blank\" rel=\"noopener\">Maleta Plegable Port\u00e1til HL 1100<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120W-Transportable-Pop-Up-Case.pdf\" target=\"_blank\" rel=\"noopener\">Maleta Plegable Port\u00e1til HL 1120<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"els-item accordion-item\"><div class=\"els-title accordion-title has-content\">\r\n                                    <span>Gu\u00edas de Instalaci\u00f3n <\/span><i class=\"icon\"><svg aria-hidden=\"true\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"currentColor\"><use xlink:href=\"#icon-btn-arrow\"><\/use><\/svg><\/i><\/div><div class=\"els-content accordion-content\"><div class=\"els-desc\"><ul>\n<li><a href=\"https:\/\/www.hughes.com\/resources\/hughes-leo-terminal-hl1100w-step-step-installation-video\">Instalaci\u00f3n Paso a Paso Terminal LEO HL1100W de Hughes (video)<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/resources\/hughes-leo-terminal-hl1120w-step-step-installation-guide-video\">Instalaci\u00f3n Paso a Paso Terminal LEO HL1200W de Hughes (video)<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/03\/Hughes-LEO-HL1100W-UT-Installation-Guide.pdf\">Gu\u00eda de Instalaci\u00f3n HL1100W-UT LEO de Hughes<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/03\/Hughes-LEO-HL1120W-UT-Installation-Guide.pdf\">Gu\u00eda de Instalaci\u00f3n HL1200W-UT LEO de Hughes<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/01\/Hughes-LEO-HL1100W-Quick-Start-Guide.pdf\">Gu\u00eda de Inicio R\u00e1pido HL 1100W LEO de Hughes<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/01\/Hughes-LEO-HL1120W-Quick-Start-Guide.pdf\">Gu\u00eda de Inicio R\u00e1pido HL 1200W LEO de Hughes<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1100-Non-Adjustable-Mobility-Mount-Installation-Manual.pdf\" target=\"_blank\" rel=\"noopener\">Gu\u00eda de Instalaci\u00f3n del Soporte para Movilidad no ajustable HL1120 LEO de Hughes<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HL1120-Non-Adjustable-Mobility-Mount-Installation-Manual.pdf\" target=\"_blank\" rel=\"noopener\">Gu\u00eda de Instalaci\u00f3n del Soporte para Movilidad no ajustable HL1100 LEO de Hughes<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"els-item accordion-item\"><div class=\"els-title accordion-title has-content\">\r\n                                    <span>Especificaciones <\/span><i class=\"icon\"><svg aria-hidden=\"true\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"currentColor\"><use xlink:href=\"#icon-btn-arrow\"><\/use><\/svg><\/i><\/div><div class=\"els-content accordion-content\"><div class=\"els-desc\"><ul>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/01\/Hughes-LEO-HL1100-Product-Spec.pdf\">Especificaciones para HL1120 LEO de Hughes<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/01\/Hughes-LEO-HL1120-Product-Specification.pdf\">Especificaciones para HL1100 LEO de Hughes<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"els-item accordion-item\"><div class=\"els-title accordion-title has-content\">\r\n                                    <span>Informaci\u00f3n para Env\u00edos<\/span><i class=\"icon\"><svg aria-hidden=\"true\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"currentColor\"><use xlink:href=\"#icon-btn-arrow\"><\/use><\/svg><\/i><\/div><div class=\"els-content accordion-content\"><div class=\"els-desc\"><ul>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/03\/HL1100W-Shipping-Information.pdf\">Informaci\u00f3n para env\u00edos HL 1100<\/a><\/li>\n<li><a href=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/03\/HL1120W-Shipping-Information.pdf\">Informaci\u00f3n para env\u00edos HL 1120<\/a><\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div>\r\n    <\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":11617,"parent":38964,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":true,"_searchwp_excluded":"","footnotes":""},"class_list":["post-38968","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Antena Electr\u00f3nicamente Orientable (ESA) para Baja \u00d3rbita Terrestre (LEO)<\/title>\n<meta name=\"description\" content=\"La \u00faltima innovaci\u00f3n disponible, ofreciendo conectividad global de alto rendimiento y baja latencia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antena Electr\u00f3nicamente Orientable (ESA) para Baja \u00d3rbita Terrestre (LEO)\" \/>\n<meta property=\"og:description\" content=\"La \u00faltima innovaci\u00f3n disponible, ofreciendo conectividad global de alto rendimiento y baja latencia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable\" \/>\n<meta property=\"og:site_name\" content=\"Hughes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HughesConnects\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T19:14:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/01\/HL1120W-Hero.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@HughesConnects\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/soluciones\\\/servicios-satelitales-systems-terrestre\\\/antena-electronicamente-orientable\",\"url\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/soluciones\\\/servicios-satelitales-systems-terrestre\\\/antena-electronicamente-orientable\",\"name\":\"Antena Electr\u00f3nicamente Orientable (ESA) para Baja \u00d3rbita Terrestre (LEO)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/soluciones\\\/servicios-satelitales-systems-terrestre\\\/antena-electronicamente-orientable#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/soluciones\\\/servicios-satelitales-systems-terrestre\\\/antena-electronicamente-orientable#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hughes.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/HL1120W-Hero.png\",\"datePublished\":\"2026-01-27T11:58:55+00:00\",\"dateModified\":\"2026-03-24T19:14:20+00:00\",\"description\":\"La \u00faltima innovaci\u00f3n disponible, ofreciendo conectividad global de alto rendimiento y baja latencia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/soluciones\\\/servicios-satelitales-systems-terrestre\\\/antena-electronicamente-orientable#breadcrumb\"},\"inLanguage\":\"es-PE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hughes.com\\\/pe\\\/soluciones\\\/servicios-satelitales-systems-terrestre\\\/antena-electronicamente-orientable\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/soluciones\\\/servicios-satelitales-systems-terrestre\\\/antena-electronicamente-orientable#primaryimage\",\"url\":\"https:\\\/\\\/www.hughes.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/HL1120W-Hero.png\",\"contentUrl\":\"https:\\\/\\\/www.hughes.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/HL1120W-Hero.png\",\"width\":1280,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/soluciones\\\/servicios-satelitales-systems-terrestre\\\/antena-electronicamente-orientable#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hughes.com\\\/pe\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soluciones\",\"item\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/soluciones\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Servicios Satelitales y Sistema Terrestre\",\"item\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/soluciones\\\/servicios-satelitales-systems-terrestre\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Antena Electr\u00f3nicamente Orientable de Hughes (ESA) para Baja \u00d3rbita Terrestre (LEO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/#website\",\"url\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/\",\"name\":\"Hughes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-PE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/#organization\",\"name\":\"Hughes\",\"url\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-PE\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hughes.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/hughes-echostarlogo.png\",\"contentUrl\":\"https:\\\/\\\/www.hughes.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/hughes-echostarlogo.png\",\"width\":696,\"height\":696,\"caption\":\"Hughes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/pe\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HughesConnects\\\/\",\"https:\\\/\\\/x.com\\\/HughesConnects\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/HughesTV\\\/videos\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3569\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antena Electr\u00f3nicamente Orientable (ESA) para Baja \u00d3rbita Terrestre (LEO)","description":"La \u00faltima innovaci\u00f3n disponible, ofreciendo conectividad global de alto rendimiento y baja latencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable","og_locale":"es_ES","og_type":"article","og_title":"Antena Electr\u00f3nicamente Orientable (ESA) para Baja \u00d3rbita Terrestre (LEO)","og_description":"La \u00faltima innovaci\u00f3n disponible, ofreciendo conectividad global de alto rendimiento y baja latencia","og_url":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable","og_site_name":"Hughes","article_publisher":"https:\/\/www.facebook.com\/HughesConnects\/","article_modified_time":"2026-03-24T19:14:20+00:00","og_image":[{"width":1280,"height":480,"url":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/01\/HL1120W-Hero.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@HughesConnects","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable","url":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable","name":"Antena Electr\u00f3nicamente Orientable (ESA) para Baja \u00d3rbita Terrestre (LEO)","isPartOf":{"@id":"https:\/\/www.hughes.com\/pe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable#primaryimage"},"image":{"@id":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable#primaryimage"},"thumbnailUrl":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/01\/HL1120W-Hero.png","datePublished":"2026-01-27T11:58:55+00:00","dateModified":"2026-03-24T19:14:20+00:00","description":"La \u00faltima innovaci\u00f3n disponible, ofreciendo conectividad global de alto rendimiento y baja latencia","breadcrumb":{"@id":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable#breadcrumb"},"inLanguage":"es-PE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable"]}]},{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable#primaryimage","url":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/01\/HL1120W-Hero.png","contentUrl":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/01\/HL1120W-Hero.png","width":1280,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hughes.com\/pe"},{"@type":"ListItem","position":2,"name":"Soluciones","item":"https:\/\/www.hughes.com\/pe\/soluciones"},{"@type":"ListItem","position":3,"name":"Servicios Satelitales y Sistema Terrestre","item":"https:\/\/www.hughes.com\/pe\/soluciones\/servicios-satelitales-systems-terrestre"},{"@type":"ListItem","position":4,"name":"Antena Electr\u00f3nicamente Orientable de Hughes (ESA) para Baja \u00d3rbita Terrestre (LEO)"}]},{"@type":"WebSite","@id":"https:\/\/www.hughes.com\/pe\/#website","url":"https:\/\/www.hughes.com\/pe\/","name":"Hughes","description":"","publisher":{"@id":"https:\/\/www.hughes.com\/pe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hughes.com\/pe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-PE"},{"@type":"Organization","@id":"https:\/\/www.hughes.com\/pe\/#organization","name":"Hughes","url":"https:\/\/www.hughes.com\/pe\/","logo":{"@type":"ImageObject","inLanguage":"es-PE","@id":"https:\/\/www.hughes.com\/pe\/#\/schema\/logo\/image\/","url":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/05\/hughes-echostarlogo.png","contentUrl":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/05\/hughes-echostarlogo.png","width":696,"height":696,"caption":"Hughes"},"image":{"@id":"https:\/\/www.hughes.com\/pe\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HughesConnects\/","https:\/\/x.com\/HughesConnects","https:\/\/www.youtube.com\/user\/HughesTV\/videos","https:\/\/www.linkedin.com\/company\/3569\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hughes.com\/pe\/wp-json\/wp\/v2\/pages\/38968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hughes.com\/pe\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hughes.com\/pe\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hughes.com\/pe\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hughes.com\/pe\/wp-json\/wp\/v2\/comments?post=38968"}],"version-history":[{"count":0,"href":"https:\/\/www.hughes.com\/pe\/wp-json\/wp\/v2\/pages\/38968\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.hughes.com\/pe\/wp-json\/wp\/v2\/pages\/38964"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hughes.com\/pe\/wp-json\/wp\/v2\/media\/11617"}],"wp:attachment":[{"href":"https:\/\/www.hughes.com\/pe\/wp-json\/wp\/v2\/media?parent=38968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}