{"id":34397,"date":"2025-12-26T09:17:08","date_gmt":"2025-12-26T09:17:08","guid":{"rendered":"https:\/\/hughes1stg.wpenginepowered.com\/home\/"},"modified":"2026-02-26T21:03:05","modified_gmt":"2026-02-26T21:03:05","slug":"home","status":"publish","type":"page","link":"https:\/\/www.hughes.com\/mx","title":{"rendered":"Home"},"content":{"rendered":"<!-- Home Hero --><section class=\"home-hero-section bg-dark\" data-aos>\r\n        <div class=\"hh-bg-media\"><picture class=\"mobile\">\r\n                            <source srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2025\/12\/404-bg-image.jpg\" media=\"(max-width: 767px)\">\r\n                            <source srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/Homepage-Hero-Background-scaled.jpg\">\r\n                            <img sizes=\"(max-width: 2560px) 100vw, 2560px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Homepage-Hero-Background-300x169.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Homepage-Hero-Background-1024x576.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Homepage-Hero-Background-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Homepage-Hero-Background-768x432.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Homepage-Hero-Background-1536x864.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Homepage-Hero-Background-2048x1152.webp 2048w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Homepage-Hero-Background-scaled.webp 2560w\" decoding=\"async\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Homepage-Hero-Background-scaled.webp\" alt=\"Rural landscape at sunset\">\r\n                        <\/picture><\/div>\r\n    <div class=\"container\">\r\n        <div class=\"hh-grid\"><div class=\"hh-left\">\r\n                    <div class=\"hh-content\"><h1 class=\"-lg\">Impulsando un Mundo M\u00e1s Conectado<\/h1><div class=\"desc -lg\"><p>En Hughes habilitamos conectividad de alto desempe\u00f1o con tecnolog\u00edas satelitales y soluciones empresariales que impulsan a organizaciones, comunidades y gobiernos en todas partes.<\/p>\n<\/div><div class=\"hh-cta d-flex\"><a class=\"btn\" href=\"https:\/\/www.hughes.com\/mx\/contactenos\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Cont\u00e1ctenos\" >Cont\u00e1ctenos<\/a><a class=\"btn -secondary\" href=\"https:\/\/www.hughes.com\/mx\/quienes-somos\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Qui\u00e9nes somos\" >Qui\u00e9nes somos<\/a><\/div><\/div>\r\n                <\/div><div class=\"hh-right\">\r\n                    <div class=\"hh-media-wrap\"><a href=\"https:\/\/youtu.be\/msqTxupLxec?si=beyANw5IiGEjgfvA\" class=\"hh-media-link\" data-fancybox><video class=\"video-inner html5\" muted playsinline preload=\"metadata\" loop>\r\n                                    <source src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/Hughes-Homepage-Teaser.mp4#t=0.01\" type=\"video\/mp4\">\r\n                                <\/video><div class=\"hh-video-cta\">\r\n                                <span class=\"btn-play\"><\/span>\r\n                                <span class=\"btn-text\">Conoce c\u00f3mo conectamos al mundo<\/span>\r\n                            <\/div>\r\n                        <\/a><\/div>\r\n                <\/div><\/div>\r\n    <\/div><\/section>\n\n<!-- Horizontal Tabs --><section class=\"horizontal-tabs-section bg-dark space-md border-radius-bottom-lr\">\r\n    <div class=\"container\"><div class=\"sec-heading text-center\" data-aos>\r\n                <h2 class=\"sec-title\">Conectividad en todas partes, sin interrupciones.<\/h2>\r\n            <\/div><div class=\"hts-wrap\"><div class=\"hts-tab-slider swiper\">\r\n                    <div class=\"hts-tab-list swiper-wrapper\"><div class=\"hts-tab-item swiper-slide is-active\" data-href=\"#hts-tab-1\">Sistema Terrestre Satelital<\/div><div class=\"hts-tab-item swiper-slide\" data-href=\"#hts-tab-2\">Servicios Satelitales<\/div><div class=\"hts-tab-item swiper-slide\" data-href=\"#hts-tab-3\">Soluciones para la Brecha Digital<\/div><div class=\"hts-tab-item swiper-slide\" data-href=\"#hts-tab-4\">Soluciones 5G<\/div><\/div>\r\n                    <div class=\"hts-animation-line\"><\/div>\r\n                <\/div><div class=\"hts-tab-content\"><div class=\"hts-tab-grid\"><div class=\"hts-tab-left\"><div class=\"hts-tab-left-wrap\" data-aos data-id=\"#hts-tab-1\"><h3 class=\"h3 title fade-up\">Sistema JUPITER\u2122 para gesti\u00f3n simple y alto rendimiento<\/h3><div class=\"desc -lg fade-up\"><p>El Sistema JUPITER\u2122 de Hughes es una plataforma satelital de alto rendimiento dise\u00f1ada para ofrecer capacidad, eficiencia y simplicidad operativa. Su arquitectura escalable permite soportar m\u00faltiples servicios, optimizar costos y garantizar conectividad confiable en cualquier entorno.<\/p>\n<\/div><div class=\"btn-wrap fade-up\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/servicios-satelitales-systems-terrestre\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"M\u00e1s sobre Sistemas Satelitales Terrestres\" ><span>M\u00e1s sobre Sistemas Satelitales Terrestres<\/span><\/a><\/div><div class=\"hts-sub-tabs\"><div class=\"hts-sub-tab fade-up\" style=\"transition-delay: 0.8s;\"><h4 class=\"h6\">Sistema JUPITER de Hughes<\/h4><div class=\"desc\"><p>Tecnolog\u00eda l\u00edder para redes satelitales<\/p>\n<\/div><div class=\"sub-btn-wrap\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/servicios-satelitales-systems-terrestre\/sistema-jupiter\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Conoce M\u00e1s\" ><span>Conoce M\u00e1s<\/span><\/a><\/div><\/div><div class=\"hts-sub-tab fade-up\" style=\"transition-delay: 1s;\"><h4 class=\"h6\">Redes Especializadas para Defensa<\/h4><div class=\"desc\"><p>Redes resilientes para operaciones seguras<\/p>\n<\/div><div class=\"sub-btn-wrap\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/comunicaciones-especializadas-de-defensa\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Conoce M\u00e1s\" ><span>Conoce M\u00e1s<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"hts-tab-left-wrap\"  data-id=\"#hts-tab-2\"><h3 class=\"h3 title fade-up\">Conectividad Satelital Confiable para Empresas y Gobierno<\/h3><div class=\"desc -lg fade-up\"><p>Soluciones de conectividad satelital de alto desempe\u00f1o que garantizan disponibilidad, continuidad operativa y cobertura en ubicaciones remotas. Ideal para empresas y gobiernos que necesitan comunicaciones confiables en cualquier entorno.<\/p>\n<\/div><div class=\"btn-wrap fade-up\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/servicios-satelitales-systems-terrestre\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"M\u00e1s sobre Servicios Satelitales\" ><span>M\u00e1s sobre Servicios Satelitales<\/span><\/a><\/div><div class=\"hts-sub-tabs\"><div class=\"hts-sub-tab fade-up\" style=\"transition-delay: 0.8s;\"><h4 class=\"h6\">Servicio LEO Gestionado<\/h4><div class=\"desc\"><p>Soluci\u00f3n gestionada LEO de baja latencia y de nivel empresarial.<\/p>\n<\/div><div class=\"sub-btn-wrap\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/servicios-satelitales-systems-terrestre\/hughes-leo\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Conoce M\u00e1s\" ><span>Conoce M\u00e1s<\/span><\/a><\/div><\/div><div class=\"hts-sub-tab fade-up\" style=\"transition-delay: 1s;\"><h4 class=\"h6\">Antena Electr\u00f3nicamente Orientable (ESA)<\/h4><div class=\"desc\"><p>Conectividad ininterrumpida con terminales de \u00faltima generaci\u00f3n<\/p>\n<\/div><div class=\"sub-btn-wrap\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/servicios-satelitales-systems-terrestre\/antena-electronicamente-orientable\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Conoce M\u00e1s\" ><span>Conoce M\u00e1s<\/span><\/a><\/div><\/div><div class=\"hts-sub-tab fade-up\" style=\"transition-delay: 1.2s;\"><h4 class=\"h6\">Flota de Sat\u00e9lites JUPITER<\/h4><div class=\"desc\"><p>Flota JUPITER\u2122 que potencia la conectividad satelital<\/p>\n<\/div><div class=\"sub-btn-wrap\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/servicios-satelitales-systems-terrestre\/flota-satelites-de-jupiter\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Conoce M\u00e1s\" ><span>Conoce M\u00e1s<\/span><\/a><\/div><\/div><div class=\"hts-sub-tab fade-up\" style=\"transition-delay: 1.4s;\"><h4 class=\"h6\">Comunicaciones de Respaldo<\/h4><div class=\"desc\"><p>Enlaces satelitales de respaldo para respuesta a emergencias<\/p>\n<\/div><div class=\"sub-btn-wrap\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/comunicaciones-de-respaldo-para-emergencias\" target=\"_self\" rel=\"nofollow\" aria-label=\"Conoce M\u00e1s\" ><span>Conoce M\u00e1s<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"hts-tab-left-wrap\"  data-id=\"#hts-tab-3\"><h3 class=\"h3 title fade-up\">Conectividad Satelital para Zonas Remotas<\/h3><div class=\"desc -lg fade-up\"><p>Hughes impulsa la conectividad mediante soluciones satelitales que permiten llevar servicios de calidad a zonas remotas o de dif\u00edcil acceso, contribuyendo al cierre de la brecha digital en M\u00e9xico.<\/p>\n<\/div><div class=\"btn-wrap fade-up\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/para-la-brecha-digital\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"M\u00e1s sobre Soluciones para la Brecha Digital\" ><span>M\u00e1s sobre Soluciones para la Brecha Digital<\/span><\/a><\/div><div class=\"hts-sub-tabs\"><div class=\"hts-sub-tab fade-up\" style=\"transition-delay: 0.8s;\"><h4 class=\"h6\">Conectividad para Escuelas<\/h4><div class=\"desc\"><p>Soluciones de Educaci\u00f3n a Distancia con Internet Satelital<\/p>\n<\/div><div class=\"sub-btn-wrap\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/para-la-brecha-digital\/conectividad-para-escuelas\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Conoce M\u00e1s\" ><span>Conoce M\u00e1s<\/span><\/a><\/div><\/div><div class=\"hts-sub-tab fade-up\" style=\"transition-delay: 1s;\"><h4 class=\"h6\">Wi-Fi Comunitario<\/h4><div class=\"desc\"><p>Conectando a los no conectados a trav\u00e9s del acceso a Wi-Fi compartido<\/p>\n<\/div><div class=\"sub-btn-wrap\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/para-la-brecha-digital\/wifi-comunitario\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Conoce M\u00e1s\" ><span>Conoce M\u00e1s<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"hts-tab-left-wrap\"  data-id=\"#hts-tab-4\"><h3 class=\"h3 title fade-up\">Impulsando el Futuro con Soluciones 5G Avanzadas<\/h3><div class=\"desc -lg fade-up\"><p>Hughes impulsa la adopci\u00f3n de 5G con soluciones que integran m\u00faltiples tecnolog\u00edas y transportes para crear redes m\u00e1s inteligentes, eficientes y resilientes, adaptadas a las necesidades de empresas, gobiernos y sectores cr\u00edticos.<\/p>\n<\/div><div class=\"btn-wrap fade-up\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/5g\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"M\u00e1s sobre Soluciones 5G\" ><span>M\u00e1s sobre Soluciones 5G<\/span><\/a><\/div><div class=\"hts-sub-tabs\"><div class=\"hts-sub-tab fade-up\" style=\"transition-delay: 0.8s;\"><h4 class=\"h6\">Backhaul Celular<\/h4><div class=\"desc\"><p>Backhaul satelital de alto desempe\u00f1o para redes m\u00f3viles<\/p>\n<\/div><div class=\"sub-btn-wrap\"><a class=\"btn-link\" href=\"https:\/\/www.hughes.com\/mx\/soluciones\/para-la-brecha-digital\/backhaul-celular\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Conoce M\u00e1s\" ><span>Conoce M\u00e1s<\/span><\/a><\/div><\/div><div class=\"hts-sub-tab fade-up\" style=\"transition-delay: 1s;\"><h4 class=\"h6\">Redes Privadas 5G<\/h4><div class=\"desc\"><p>Redes 5G privadas para operaciones seguras y de alto desempe\u00f1o<\/p>\n<\/div><\/div><\/div><\/div><\/div>\r\n                        <div class=\"hts-tab-right\">\r\n                            <div class=\"hts-tab-image-wrap\" data-aos><div class=\"hts-tab-image\" data-id=\"#hts-tab-1\" data-aos><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Satellite-Systems.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Satellite-Systems-194x300.webp 194w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Satellite-Systems-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Satellite-Systems.webp 400w\" sizes=\"(max-width: 400px) 100vw, 400px\" alt=\"Hughes Satellite Systems\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"620\"><\/div><div class=\"hts-tab-image\" data-id=\"#hts-tab-2\" ><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Servicios-Satelitales.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Servicios-Satelitales-200x300.webp 200w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Servicios-Satelitales-683x1024.webp 683w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Servicios-Satelitales-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Servicios-Satelitales-768x1152.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Servicios-Satelitales.webp 1024w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" alt=\"Servicios Satelitales\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1536\"><\/div><div class=\"hts-tab-image\" data-id=\"#hts-tab-3\" ><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Brecha-Digital.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Brecha-Digital-200x300.webp 200w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Brecha-Digital-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Brecha-Digital.webp 600w\" sizes=\"(max-width: 600px) 100vw, 600px\" alt=\"young latin american boy using tablet device\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"900\"><\/div><div class=\"hts-tab-image\" data-id=\"#hts-tab-4\" ><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Soluciones-5G.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Soluciones-5G-194x300.webp 194w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Soluciones-5G-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Soluciones-5G.webp 400w\" sizes=\"(max-width: 400px) 100vw, 400px\" alt=\"Soluciones 5G\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"620\"><\/div><\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div><\/div>\r\n<\/section>\n\n<!-- Full-width Media Tabs --><section class=\"full-width-media-tabs-section checked space-lg-m\">\r\n    <div class=\"container\"><div class=\"sec-heading\"><h2 class=\"h2\">La Ventaja de una Conectividad H\u00edbrida<\/h2><div class=\"desc\"><p>Un futuro verdaderamente conectado depende de integrar \u00f3rbitas, transportes y tecnolog\u00edas inteligentes en soluciones totalmente unificadas. Hughes impulsa esta visi\u00f3n con su red h\u00edbrida y su capacidad \u00fanica para combinar distintas tecnolog\u00edas y ofrecer comunicaciones confiables a escala global.<\/p>\n<\/div><div class=\"btn-wrap\"><a class=\"btn-link -lg\" href=\"https:\/\/www.hughes.com\/mx\/quienes-somos\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Conoce M\u00e1s\" ><span>Conoce M\u00e1s<\/span><\/a><\/div><\/div><div class=\" fwmt-no-autoplay\"><video autoplay loop muted playsinline webkit-playsinline class=\"d-none d-md-block\">\r\n                                <source src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/Hughes-Orb-higher-res.mp4#t=0.1\" type=\"video\/mp4\">\r\n                            <\/video><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Connected-Globe-sized-mobile.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Connected-Globe-sized-mobile-300x300.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Connected-Globe-sized-mobile-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Connected-Globe-sized-mobile-768x768.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Connected-Globe-sized-mobile.webp 1000w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" alt=\"Abstract connected globe\" class=\"d-md-none d-block\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\"><\/div><div class=\"fwmt-wrap\"><div class=\"fwmt-tab-list\"><div class=\"fwmt-tab-item\">\r\n                                <div class=\"fwmt-tab-content\"><p><strong>Flota GEO<\/strong> basada en el Sistema JUPITER\u2122 que incluye a JUPITER\u2122 3 \u2014el sat\u00e9lite comercial de telecomunicaciones m\u00e1s grande del mundo\u2014 para m\u00e1xima capacidad, eficiencia y amplia cobertura.<\/p>\n<\/div><\/div><div class=\"fwmt-tab-item\">\r\n                                <div class=\"fwmt-tab-content\"><p><strong>Constelaci\u00f3n LEO en alianza con Eutelsat OneWeb<\/strong> que aporta baja latencia y continuidad, integrada a nuestros servicios gestionados para habilitar operaciones remotas y m\u00f3viles.<\/p>\n<\/div><\/div><div class=\"fwmt-tab-item\">\r\n                                <div class=\"fwmt-tab-content\"><p><strong>Redes 5G de nueva generaci\u00f3n<\/strong> que brindan baja latencia, alta capacidad y control de extremo a extremo para aplicaciones cr\u00edticas e industriales.<\/p>\n<\/div><\/div><\/div>\r\n                <\/div><\/div>\r\n<\/section>\n\n<!-- Image Carousel w\/ Stats --><section class=\"image-carousel-stats-section space-lg-m border-radius-bottom-lr\">\r\n    <div class=\"container\"><div class=\"sec-heading text-center\"><h2 class=\"h2\">M\u00e1s de 50 a\u00f1os creando el futuro de la conectividad<\/h2><div class=\"desc -lg\"><p>Desde la creaci\u00f3n del Internet satelital en los 90 hasta d\u00e9cadas de innovaci\u00f3n continua, Hughes ha redefinido c\u00f3mo el mundo se conecta durante m\u00e1s de 50 a\u00f1os.<\/p>\n<\/div><\/div><div class=\"icss-carsousel splide\">\r\n                <div class=\"splide__track\">\r\n                    <div class=\"icss-img-list splide__list\"><div class=\"icss-img-item splide__slide\">\r\n                                    <div class=\"icss-img\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/LEO-Satellite-243x370-1.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/LEO-Satellite-243x370-1-197x300.webp 197w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/LEO-Satellite-243x370-1-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/LEO-Satellite-243x370-1.webp 243w\" sizes=\"(max-width: 243px) 100vw, 243px\" alt=\"innovation in LEO satellites\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"243\" height=\"370\"><\/div>\r\n                                <\/div><div class=\"icss-img-item splide__slide\">\r\n                                    <div class=\"icss-img\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Cellular-Backhaul-335x212-1.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Cellular-Backhaul-335x212-1-300x190.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Cellular-Backhaul-335x212-1-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Cellular-Backhaul-335x212-1.webp 335w\" sizes=\"(max-width: 335px) 100vw, 335px\" alt=\"innovation in cell backhaul\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"335\" height=\"212\"><\/div>\r\n                                <\/div><div class=\"icss-img-item splide__slide\">\r\n                                    <div class=\"icss-img\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Aeronaves_388x367.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Aeronaves_388x367-300x284.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Aeronaves_388x367-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Aeronaves_388x367.webp 388w\" sizes=\"(max-width: 388px) 100vw, 388px\" alt=\"Home Image\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"367\"><\/div>\r\n                                <\/div><div class=\"icss-img-item splide__slide\">\r\n                                    <div class=\"icss-img\"><img sizes=\"(max-width: 240px) 100vw, 240px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/5G-Network-240x209-1-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/5G-Network-240x209-1.webp 240w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/5G-Network-240x209-1.webp\" alt=\"innovation in 5G networks\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"209\"><\/div>\r\n                                <\/div><div class=\"icss-img-item splide__slide\">\r\n                                    <div class=\"icss-img\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Logistics-243x370-1.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Logistics-243x370-1-197x300.webp 197w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Logistics-243x370-1-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Logistics-243x370-1.webp 243w\" sizes=\"(max-width: 243px) 100vw, 243px\" alt=\"innovation in logistics\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"243\" height=\"370\"><\/div>\r\n                                <\/div><div class=\"icss-img-item splide__slide\">\r\n                                    <div class=\"icss-img\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/GEO-Satellite-335x212-1.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/GEO-Satellite-335x212-1-300x190.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/GEO-Satellite-335x212-1-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/GEO-Satellite-335x212-1.webp 335w\" sizes=\"(max-width: 335px) 100vw, 335px\" alt=\"innovation in GEO satellites\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"335\" height=\"212\"><\/div>\r\n                                <\/div><div class=\"icss-img-item splide__slide\">\r\n                                    <div class=\"icss-img\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Satellite-TV-388x367-1.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Satellite-TV-388x367-1-300x284.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Satellite-TV-388x367-1-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Satellite-TV-388x367-1.webp 388w\" sizes=\"(max-width: 388px) 100vw, 388px\" alt=\"innovation in satellite TV\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"388\" height=\"367\"><\/div>\r\n                                <\/div><div class=\"icss-img-item splide__slide\">\r\n                                    <div class=\"icss-img\"><img sizes=\"(max-width: 240px) 100vw, 240px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sitios-Empresariales_240x209-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sitios-Empresariales_240x209.webp 240w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sitios-Empresariales_240x209.webp\" alt=\"Home Image\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"209\"><\/div>\r\n                                <\/div><div class=\"icss-img-item splide__slide\">\r\n                                    <div class=\"icss-img\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Classroom-243x370-1.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Classroom-243x370-1-197x300.webp 197w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Classroom-243x370-1-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Classroom-243x370-1.webp 243w\" sizes=\"(max-width: 243px) 100vw, 243px\" alt=\"innovation in the classroom\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"243\" height=\"370\"><\/div>\r\n                                <\/div><div class=\"icss-img-item splide__slide\">\r\n                                    <div class=\"icss-img\"><img src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comms-on-the-Pause-335x212-1.webp\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comms-on-the-Pause-335x212-1-300x190.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comms-on-the-Pause-335x212-1-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comms-on-the-Pause-335x212-1.webp 335w\" sizes=\"(max-width: 335px) 100vw, 335px\" alt=\"innovation in COTP\" class=\"\" loading=\"lazy\" decoding=\"async\" width=\"335\" height=\"212\"><\/div>\r\n                                <\/div><\/div>\r\n                <\/div>\r\n            <\/div><div class=\"icss-stats-carousel swiper\">\r\n                <div class=\"swiper-wrapper\"><div class=\"icss-stat swiper-slide\">\r\n                                <div class=\"icss-stat-wrap\"><div class=\"number\">85<\/div><p class=\"desc\">El Sistema JUPITER de Hughes opera en m\u00e1s de 85 sat\u00e9lites de operadores a nivel global<\/p><\/div>\r\n                            <\/div><div class=\"icss-stat swiper-slide\">\r\n                                <div class=\"icss-stat-wrap\"><div class=\"number\">500k<\/div><p class=\"desc\">Sitios Empresariales y de Gobierno cuentan con el soporte de Hughes a nivel global<\/p><\/div>\r\n                            <\/div><div class=\"icss-stat swiper-slide\">\r\n                                <div class=\"icss-stat-wrap\"><div class=\"number\">10k<\/div><p class=\"desc\">Terminales ESA fabricados y entregados por Hughes<\/p><\/div>\r\n                            <\/div><div class=\"icss-stat swiper-slide\">\r\n                                <div class=\"icss-stat-wrap\"><div class=\"number\">12k<\/div><p class=\"desc\">Sitios de Backhaul Celular impulsados por Hughes a n\u00edvel global<\/p><\/div>\r\n                            <\/div><div class=\"icss-stat swiper-slide\">\r\n                                <div class=\"icss-stat-wrap\"><div class=\"number\">+50<\/div><p class=\"desc\">A\u00f1os de experiencia conectando personas, empresas y cosas<\/p><\/div>\r\n                            <\/div><\/div>\r\n                <div class=\"icss-slider-arrow swiper-arrow\">\r\n                    <button class=\"icss-button-prev swiper-button-prev\"><svg aria-hidden=\"true\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"currentColor\"><use xlink:href=\"#icon-btn-arrow\"><\/use><\/svg><\/button>\r\n                    <button class=\"icss-button-next swiper-button-next\"><svg aria-hidden=\"true\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"currentColor\"><use xlink:href=\"#icon-btn-arrow\"><\/use><\/svg><\/button>\r\n                <\/div>\r\n            <\/div><\/div>\r\n<\/section>\n\n<!-- Logo Carousel --><section class=\"logo-carousel-section space-lg-m\"><div class=\"container\">\n            <div class=\"sec-heading text-center\">\n                <h2>Confiable a Nivel Global<\/h2>\n            <\/div>\n        <\/div><div class=\"lcs-wrap\"><div class=\"lcs-list\" data-aos><div class=\"lcs-item\" style=\"--delay:0s\">\n                        <div class=\"lcs-logo-slider splide\">\n                            <div class=\"splide__track\">\n                                <div class=\"lcs-logo-list splide__list\"><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 371px) 100vw, 371px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BatteriesPlus-Logo-300x68.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BatteriesPlus-Logo-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BatteriesPlus-Logo-768x174.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BatteriesPlus-Logo-e1773876454996.webp 371w\" fetchpriority=\"high\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BatteriesPlus-Logo-e1773876454996.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"827\" height=\"187\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 336px) 100vw, 336px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Veolia_logo-300x75.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Veolia_logo-1024x256.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Veolia_logo-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Veolia_logo-768x192.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Veolia_logo-1536x384.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Veolia_logo-2048x512.webp 2048w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Veolia_logo-e1773876463232.webp 336w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Veolia_logo-e1773876463232.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"2560\" height=\"640\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 99px) 100vw, 99px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Albertsons-300x254.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Albertsons-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Albertsons-768x649.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Albertsons-e1773876472821.webp 99w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Albertsons-e1773876472821.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"784\" height=\"663\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 249px) 100vw, 249px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ahold-Delhaize-300x101.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ahold-Delhaize-1024x346.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ahold-Delhaize-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ahold-Delhaize-768x260.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ahold-Delhaize-e1773876483678.webp 249w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ahold-Delhaize-e1773876483678.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1494\" height=\"505\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 107px) 100vw, 107px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Wipro-300x236.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Wipro-1024x806.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Wipro-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Wipro-768x605.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Wipro-e1773877148697.webp 107w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Wipro-e1773877148697.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1181\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 527px) 100vw, 527px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Siemens-300x48.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Siemens-1024x163.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Siemens-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Siemens-768x122.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Siemens-1536x245.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Siemens-2048x326.webp 2048w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Siemens-e1773876622587.webp 527w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Siemens-e1773876622587.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"2560\" height=\"408\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 178px) 100vw, 178px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-300x141.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-1024x482.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-768x361.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-e1773876603242.webp 178w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-e1773876603242.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"706\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 215px) 100vw, 215px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sterlite_Technologies_Limited-300x117.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sterlite_Technologies_Limited-1024x399.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sterlite_Technologies_Limited-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sterlite_Technologies_Limited-768x300.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sterlite_Technologies_Limited-1536x599.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sterlite_Technologies_Limited-e1773876581756.webp 215w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sterlite_Technologies_Limited-e1773876581756.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"2000\" height=\"780\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 316px) 100vw, 316px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Vodafone_2017-300x80.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Vodafone_2017-1024x272.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Vodafone_2017-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Vodafone_2017-768x204.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Vodafone_2017-1536x408.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Vodafone_2017-2048x544.webp 2048w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Vodafone_2017-e1773876503932.webp 316w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Vodafone_2017-e1773876503932.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"2557\" height=\"679\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 84px) 100vw, 84px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Shell-300x300.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Shell-1024x1024.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Shell-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Shell-768x768.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Shell-e1773876646440.webp 84w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Shell-e1773876646440.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1500\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 84px) 100vw, 84px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-300x300.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-1024x1024.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-768x768.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-e1773876868516.webp 84w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-e1773876868516.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1500\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 84px) 100vw, 84px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TOTAL-300x300.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TOTAL-1024x1024.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TOTAL-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TOTAL-768x768.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TOTAL-e1773876515614.webp 84w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TOTAL-e1773876515614.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1500\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 91px) 100vw, 91px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TATA-300x276.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TATA-1024x941.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TATA-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TATA-768x706.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TATA-e1773876533808.webp 91w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/TATA-e1773876533808.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1378\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 157px) 100vw, 157px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/airtel-300x160.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/airtel-1024x547.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/airtel-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/airtel-768x411.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/airtel-e1773877048828.webp 157w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/airtel-e1773877048828.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"802\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 280px) 100vw, 280px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Hitachi-300x90.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Hitachi-1024x308.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Hitachi-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Hitachi-768x231.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Hitachi-e1773876876534.webp 280w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Hitachi-e1773876876534.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1501\" height=\"451\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 184px) 100vw, 184px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sportsmans-Warehouse-01--300x137.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sportsmans-Warehouse-01--1024x468.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sportsmans-Warehouse-01--150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sportsmans-Warehouse-01--768x351.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sportsmans-Warehouse-01--1536x702.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sportsmans-Warehouse-01--2048x936.webp 2048w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sportsmans-Warehouse-01--e1773877739278.webp 184w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Sportsmans-Warehouse-01--e1773877739278.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"2486\" height=\"1136\"><\/div>\n                        <\/div><\/div><\/div><\/div><\/div><div class=\"lcs-item\" style=\"--delay:0.2s\">\n                        <div class=\"lcs-logo-slider splide\">\n                            <div class=\"splide__track\">\n                                <div class=\"lcs-logo-list splide__list\"><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 240px) 100vw, 240px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/State-Bank-of-India-300x105.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/State-Bank-of-India-1024x358.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/State-Bank-of-India-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/State-Bank-of-India-768x268.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/State-Bank-of-India-e1773876590115.webp 240w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/State-Bank-of-India-e1773876590115.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"524\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 178px) 100vw, 178px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-300x141.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-1024x482.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-768x361.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-e1773876603242.webp 178w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SITA-e1773876603242.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"706\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 121px) 100vw, 121px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance-Industries-300x208.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance-Industries-1024x709.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance-Industries-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance-Industries-768x531.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance-Industries-e1773876662376.webp 121w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance-Industries-e1773876662376.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1038\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 84px) 100vw, 84px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance_Jio-300x300.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance_Jio-1024x1024.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance_Jio-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance_Jio-768x768.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance_Jio-e1773876680264.webp 84w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Reliance_Jio-e1773876680264.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1500\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 84px) 100vw, 84px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ONGC-300x300.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ONGC-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ONGC-e1773876692510.webp 84w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ONGC-e1773876692510.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"600\" height=\"600\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 84px) 100vw, 84px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Nayara_Energy-300x300.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Nayara_Energy-1024x1024.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Nayara_Energy-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Nayara_Energy-768x768.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Nayara_Energy-e1773876705579.webp 84w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Nayara_Energy-e1773876705579.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1500\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 171px) 100vw, 171px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ministry_of_Defence_India-300x147.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ministry_of_Defence_India-1024x503.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ministry_of_Defence_India-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ministry_of_Defence_India-768x377.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ministry_of_Defence_India-e1773876753362.webp 171w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Ministry_of_Defence_India-e1773876753362.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"737\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 81px) 100vw, 81px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ITC_Limited-288x300.webp 288w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ITC_Limited-983x1024.webp 983w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ITC_Limited-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ITC_Limited-768x800.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ITC_Limited-1474x1536.webp 1474w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ITC_Limited-e1773876790647.webp 81w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ITC_Limited-e1773876790647.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1563\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 87px) 100vw, 87px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Space_Research_Organisation_Logo.svg-300x290.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Space_Research_Organisation_Logo.svg-1024x990.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Space_Research_Organisation_Logo.svg-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Space_Research_Organisation_Logo.svg-768x743.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Space_Research_Organisation_Logo.svg-1536x1485.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Space_Research_Organisation_Logo.svg-2048x1980.webp 2048w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Space_Research_Organisation_Logo.svg-e1773876800951.webp 87w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Space_Research_Organisation_Logo.svg-e1773876800951.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"2560\" height=\"2475\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 112px) 100vw, 112px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Oil-300x225.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Oil-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Oil-768x576.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Oil-e1773876823633.webp 112w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Indian_Oil-e1773876823633.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1024\" height=\"768\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 417px) 100vw, 417px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ICICI_Bank-300x60.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ICICI_Bank-1024x206.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ICICI_Bank-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ICICI_Bank-768x155.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ICICI_Bank-e1773876837766.webp 417w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ICICI_Bank-e1773876837766.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"302\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 68px) 100vw, 68px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-Petroleum-242x300.webp 242w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-Petroleum-827x1024.webp 827w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-Petroleum-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-Petroleum-768x951.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-Petroleum-e1773876846223.webp 68w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HP-Petroleum-e1773876846223.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1211\" height=\"1500\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 485px) 100vw, 485px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HDFC_Bank-300x52.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HDFC_Bank-1024x177.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HDFC_Bank-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HDFC_Bank-768x133.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HDFC_Bank-e1773876885104.webp 485w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/HDFC_Bank-e1773876885104.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"260\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 321px) 100vw, 321px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Harris-Corporation-300x79.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Harris-Corporation-1024x268.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Harris-Corporation-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Harris-Corporation-768x201.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Harris-Corporation-e1773876911763.webp 321w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Harris-Corporation-e1773876911763.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"393\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 201px) 100vw, 201px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/FIS-300x125.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/FIS-1024x428.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/FIS-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/FIS-768x321.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/FIS-e1773876920764.webp 201w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/FIS-e1773876920764.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"627\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 147px) 100vw, 147px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ERNET-300x172.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ERNET-1024x586.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ERNET-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ERNET-768x440.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ERNET-e1773876931119.webp 147w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ERNET-e1773876931119.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"859\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 256px) 100vw, 256px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/EPS-300x98.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/EPS-1024x336.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/EPS-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/EPS-768x252.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/EPS-e1773876939704.webp 256w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/EPS-e1773876939704.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"492\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 110px) 100vw, 110px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Diebold_Nixdorf-300x228.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Diebold_Nixdorf-1024x780.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Diebold_Nixdorf-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Diebold_Nixdorf-768x585.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Diebold_Nixdorf-e1773876955656.webp 110w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Diebold_Nixdorf-e1773876955656.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1142\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 84px) 100vw, 84px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Chhattisgarh-300x300.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Chhattisgarh-1024x1024.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Chhattisgarh-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Chhattisgarh-768x768.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Chhattisgarh-1536x1536.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Chhattisgarh-e1773876969306.webp 84w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Chhattisgarh-e1773876969306.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1667\" height=\"1667\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 82px) 100vw, 82px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BSNL-293x300.webp 293w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BSNL-1000x1024.webp 1000w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BSNL-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BSNL-768x786.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BSNL-e1773876980770.webp 82w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/BSNL-e1773876980770.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1536\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 67px) 100vw, 67px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bharat_Petroleum-240x300.webp 240w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bharat_Petroleum-818x1024.webp 818w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bharat_Petroleum-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bharat_Petroleum-768x962.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bharat_Petroleum-e1773876993695.webp 67w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bharat_Petroleum-e1773876993695.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1198\" height=\"1500\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 177px) 100vw, 177px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bank-of-India-300x142.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bank-of-India-1024x485.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bank-of-India-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bank-of-India-768x364.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bank-of-India-e1773877004518.webp 177w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Bank-of-India-e1773877004518.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"710\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 498px) 100vw, 498px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Baker_Hughes-300x51.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Baker_Hughes-1024x173.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Baker_Hughes-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Baker_Hughes-768x130.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Baker_Hughes-e1773877017726.webp 498w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Baker_Hughes-e1773877017726.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"253\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 266px) 100vw, 266px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/anuvu-300x95.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/anuvu-1024x324.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/anuvu-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/anuvu-768x243.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/anuvu-e1773877035226.webp 266w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/anuvu-e1773877035226.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"474\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 317px) 100vw, 317px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/AFCONS-300x80.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/AFCONS-1024x272.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/AFCONS-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/AFCONS-768x204.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/AFCONS-e1773877092219.webp 317w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/AFCONS-e1773877092219.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"398\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 126px) 100vw, 126px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ADANI-WELSPUN-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ADANI-WELSPUN-e1773877136302.webp 126w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ADANI-WELSPUN-e1773877136302.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"300\" height=\"200\"><\/div>\n                        <\/div><\/div><\/div><\/div><\/div><div class=\"lcs-item\" style=\"--delay:0.4s\">\n                        <div class=\"lcs-logo-slider splide\">\n                            <div class=\"splide__track\">\n                                <div class=\"lcs-logo-list splide__list\"><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 173px) 100vw, 173px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ufinet-300x146.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ufinet-1024x498.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ufinet-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ufinet-768x374.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ufinet-e1773877159542.webp 173w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ufinet-e1773877159542.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"730\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 117px) 100vw, 117px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Tigo-300x216.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Tigo-1024x737.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Tigo-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Tigo-768x553.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Tigo-e1773877167740.webp 117w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Tigo-e1773877167740.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1080\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 492px) 100vw, 492px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Telespazio-300x51.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Telespazio-1024x175.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Telespazio-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Telespazio-768x131.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Telespazio-e1773877276921.webp 492w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Telespazio-e1773877276921.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"256\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 168px) 100vw, 168px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/STC-300x150.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/STC-1024x512.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/STC-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/STC-768x384.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/STC-e1773877287566.webp 168w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/STC-e1773877287566.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"750\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 262px) 100vw, 262px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SES_new-300x96.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SES_new-1024x328.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SES_new-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SES_new-768x246.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SES_new-e1773877327144.webp 262w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SES_new-e1773877327144.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"481\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 333px) 100vw, 333px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEMAR-300x76.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEMAR-1024x258.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEMAR-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEMAR-768x194.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEMAR-e1773877344777.webp 333w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEMAR-e1773877344777.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"378\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 409px) 100vw, 409px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEDENA-300x62.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEDENA-1024x210.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEDENA-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEDENA-768x158.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEDENA-e1773877355951.webp 409w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/SEDENA-e1773877355951.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"308\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 179px) 100vw, 179px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Pasifik-Satelit-Nusantara_PSN-300x141.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Pasifik-Satelit-Nusantara_PSN-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Pasifik-Satelit-Nusantara_PSN-e1773877366427.webp 179w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Pasifik-Satelit-Nusantara_PSN-e1773877366427.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"426\" height=\"200\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 116px) 100vw, 116px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Mexsat-300x218.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Mexsat-1024x743.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Mexsat-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Mexsat-768x557.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Mexsat-e1773877374825.webp 116w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Mexsat-e1773877374825.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1088\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 112px) 100vw, 112px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Measat-300x225.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Measat-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Measat-e1773877391713.webp 112w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Measat-e1773877391713.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"577\" height=\"433\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 165px) 100vw, 165px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/LEN-300x153.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/LEN-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/LEN-768x391.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/LEN-e1773877409756.webp 165w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/LEN-e1773877409756.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"802\" height=\"408\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 420px) 100vw, 420px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Intercorp-300x60.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Intercorp-1024x205.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Intercorp-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Intercorp-768x154.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Intercorp-e1773877422186.webp 420w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Intercorp-e1773877422186.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"300\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 342px) 100vw, 342px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Eutelsat-300x74.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Eutelsat-1024x251.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Eutelsat-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Eutelsat-768x188.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Eutelsat-e1773877448375.webp 342w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Eutelsat-e1773877448375.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"368\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 109px) 100vw, 109px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ETB-300x231.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ETB-1024x788.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ETB-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ETB-768x591.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ETB-e1773877460517.webp 109w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/ETB-e1773877460517.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1500\" height=\"1155\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 231px) 100vw, 231px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comision_Federal_de_Electricidad_CFE-300x109.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comision_Federal_de_Electricidad_CFE-1024x372.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comision_Federal_de_Electricidad_CFE-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comision_Federal_de_Electricidad_CFE-768x279.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comision_Federal_de_Electricidad_CFE-1536x558.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comision_Federal_de_Electricidad_CFE-2048x744.webp 2048w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comision_Federal_de_Electricidad_CFE-scaled-e1773877471556.webp 231w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Comision_Federal_de_Electricidad_CFE-scaled-e1773877471556.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"2560\" height=\"930\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 84px) 100vw, 84px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Claro-300x300.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Claro-1024x1024.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Claro-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Claro-768x768.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Claro-1536x1536.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Claro-e1773877483648.webp 84w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Claro-e1773877483648.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1800\" height=\"1800\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 295px) 100vw, 295px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/America_Movil-300x85.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/America_Movil-1024x291.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/America_Movil-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/America_Movil-768x218.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/America_Movil-1536x437.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/America_Movil-e1773877497410.webp 295w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/America_Movil-e1773877497410.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"1800\" height=\"512\"><\/div>\n                        <\/div><div class=\"lcs-logo-item splide__slide\">\n                            <div class=\"lcs-logo\"><img sizes=\"(max-width: 376px) 100vw, 376px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Airbus_logo-300x67.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Airbus_logo-1024x229.webp 1024w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Airbus_logo-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Airbus_logo-768x172.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Airbus_logo-1536x343.webp 1536w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Airbus_logo-2048x458.webp 2048w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Airbus_logo-scaled-e1773877558452.webp 376w\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/02\/Airbus_logo-scaled-e1773877558452.webp\" alt=\"Home Image\" class=\"\" loading=\"eager\" decoding=\"async\" width=\"2560\" height=\"572\"><\/div>\n                        <\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n\n<!-- Latest Updates--><section class=\"latest-updates space-lg-m\">\r\n    <div class=\"container\">\r\n        <div class=\"lu-wrapper\"><div class=\"lu-row row\">\r\n                <div class=\"lu-col cell-lg-6\"><div class=\"lu-heading\">\r\n                            <h2>Novedades de Hughes<\/h2>\r\n                        <\/div><div class=\"lu-colwrap\">\r\n\t\t\t\t<div class=\"lu-left\">\r\n\t\t\t\t\t<a class=\"lu-featured-card\" href=\"https:\/\/www.hughes.com\/mx\/recursos\/blog\/innovacion-continua-hughes-y-la-historia-de-los-satelites\"  title=\"Innovaci\u00f3n continua: Hughes y la historia de los sat\u00e9lites\" target=\"_self\" ><div class=\"lu-bg\"><img sizes=\"(max-width: 814px) 100vw, 814px\" srcset=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/01\/Jupiter3-in-space-300x157.webp 300w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/01\/Jupiter3-in-space-150x150.webp 150w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/01\/Jupiter3-in-space-768x403.webp 768w, https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/01\/Jupiter3-in-space.webp 814w\" decoding=\"async\" src=\"https:\/\/www.hughes.com\/wp-content\/uploads\/webp\/2026\/01\/Jupiter3-in-space.webp\" alt=\"Innovaci\u00f3n continua: Hughes y la historia de los sat\u00e9lites\" class=\"\" loading=\"lazy\" width=\"814\" height=\"427\"><\/div><div class=\"lu-featured-meta\"><span class=\"lu-featured-cat\">Blog<\/span><h3 class=\"h6\">Innovaci\u00f3n continua: Hughes y la historia de los sat\u00e9lites<\/h3><\/div>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div><\/div><div class=\"lu-col cell-lg-6\">\r\n                    <div class=\"lu-colwrap\"><a class=\"btn-link lu-top-btn\" href=\"https:\/\/www.hughes.com\/mx\/recursos\/blog\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Descubre M\u00e1s\" ><span>Descubre M\u00e1s<\/span><\/a><div class=\"lu-rightwrap\"><a href=\"https:\/\/www.hughes.com\/mx\/recursos\/prensa\/hughes-aprovecha-la-solucion-hisky-para-proporcionar-conectividad-un-cliente-del\"  title=\"Hughes aprovecha la soluci\u00f3n hiSky para proporcionar conectividad a un cliente del sector energ\u00e9tico en Brasil\" target=\"_self\" class=\"lu-list-card\" ><span class=\"list-cat\">Press Release<\/span><h4 class=\"h6\">Hughes aprovecha la soluci\u00f3n hiSky para proporcionar conectividad a un cliente del sector energ\u00e9tico en Brasil<\/h4><\/a><a href=\"https:\/\/www.hughes.com\/mx\/recursos\/prensa\/hughes-es-reconocido-por-ericsson-como-socio-del-ano\"  title=\"Hughes es reconocido por Ericsson como Socio del A\u00f1o\" target=\"_self\" class=\"lu-list-card\" ><span class=\"list-cat\">Press Release<\/span><h4 class=\"h6\">Hughes es reconocido por Ericsson como Socio del A\u00f1o<\/h4><\/a><a href=\"https:\/\/www.hughes.com\/mx\/recursos\/prensa\/antena-electronicamente-orientable-esa-de-hughes-mejorara-experiencia-de-los\"  title=\"Antena Electr\u00f3nicamente Orientable (ESA) de Hughes mejorar\u00e1 experiencia de los usuarios a bordo\" target=\"_self\" class=\"lu-list-card\" ><span class=\"list-cat\">Press Release<\/span><h4 class=\"h6\">Antena Electr\u00f3nicamente Orientable (ESA) de Hughes mejorar\u00e1 experiencia de los usuarios a bordo<\/h4><\/a><\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\n\n<!-- Full-Width CTA --><section class=\"full-width-cta-section border-radius-top-lr left bg-gradient\">\r\n        <div class=\"container\">\r\n            <div class=\"fwc-row row align-items-center\"><div class=\"fwc-left cell-md-7\">\r\n                        <div class=\"fwc-content\"><h2 class=\"fwc-title\">Conecta con el equipo experto de Hughes<\/h2><div class=\"desc\"><p>Habla con nuestros especialistas y descubre c\u00f3mo mejorar tu conectividad, optimizar procesos y asegurar operaciones activas con tecnolog\u00eda satelital avanzada.<\/p>\n<\/div><\/div><\/div><div class=\"fwc-right cell-md-5\"><div class=\"btn-wrap text-left text-md-right\"><a class=\"btn -secondary\" href=\"https:\/\/www.hughes.com\/mx\/contactenos\/\" target=\"_self\" rel=\"nofollow\" aria-label=\"Cont\u00e1ctenos\" >Cont\u00e1ctenos<\/a><\/div><\/div><\/div>\r\n        <\/div>\r\n    <\/section>","protected":false},"excerpt":{"rendered":"<p>Tecnolog\u00eda satelital avanzada y servicios empresariales dise\u00f1ados para asegurar operaci\u00f3n cr\u00edtica, redes estables y continuidad en los entornos m\u00e1s exigentes.<\/p>\n","protected":false},"author":1,"featured_media":30997,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/frontpage.php","meta":{"_acf_changed":true,"_searchwp_excluded":"","footnotes":""},"class_list":["post-34397","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hughes | Conectividad satelital y soluciones empresariales<\/title>\n<meta name=\"description\" content=\"Tecnolog\u00eda satelital avanzada y servicios empresariales dise\u00f1ados para asegurar operaci\u00f3n cr\u00edtica, redes estables y continuidad en los entornos m\u00e1s exigentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hughes.com\/mx\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hughes | Conectividad satelital y soluciones empresariales\" \/>\n<meta property=\"og:description\" content=\"Tecnolog\u00eda satelital avanzada y servicios empresariales dise\u00f1ados para asegurar operaci\u00f3n cr\u00edtica, redes estables y continuidad en los entornos m\u00e1s exigentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hughes.com\/mx\" \/>\n<meta property=\"og:site_name\" content=\"Hughes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HughesConnects\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T21:03:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HughesGlobalOpenGraph.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Hughes | Conectividad satelital y soluciones empresariales\" \/>\n<meta name=\"twitter:description\" content=\"Tecnolog\u00eda satelital avanzada y servicios empresariales dise\u00f1ados para asegurar operaci\u00f3n cr\u00edtica, redes estables y continuidad en los entornos m\u00e1s exigentes.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HughesGlobalOpenGraph.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@HughesConnects\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx\",\"url\":\"https:\\\/\\\/www.hughes.com\\\/mx\",\"name\":\"Hughes | Conectividad satelital y soluciones empresariales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hughes.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/HughesGlobalOpenGraph.jpg\",\"datePublished\":\"2025-12-26T09:17:08+00:00\",\"dateModified\":\"2026-02-26T21:03:05+00:00\",\"description\":\"Tecnolog\u00eda satelital avanzada y servicios empresariales dise\u00f1ados para asegurar operaci\u00f3n cr\u00edtica, redes estables y continuidad en los entornos m\u00e1s exigentes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hughes.com\\\/mx\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx#primaryimage\",\"url\":\"https:\\\/\\\/www.hughes.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/HughesGlobalOpenGraph.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hughes.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/HughesGlobalOpenGraph.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Hughes Global\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hughes.com\\\/mx\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/www.hughes.com\\\/mx\\\/\",\"name\":\"Hughes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hughes.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx\\\/#organization\",\"name\":\"Hughes\",\"url\":\"https:\\\/\\\/www.hughes.com\\\/mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hughes.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/HughesEchoStar_Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.hughes.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/HughesEchoStar_Logo.png\",\"width\":593,\"height\":213,\"caption\":\"Hughes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hughes.com\\\/mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HughesConnects\\\/\",\"https:\\\/\\\/x.com\\\/HughesConnects\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/HughesTV\\\/videos\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3569\\\/admin\\\/dashboard\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hughes | Conectividad satelital y soluciones empresariales","description":"Tecnolog\u00eda satelital avanzada y servicios empresariales dise\u00f1ados para asegurar operaci\u00f3n cr\u00edtica, redes estables y continuidad en los entornos m\u00e1s exigentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hughes.com\/mx","og_locale":"es_ES","og_type":"article","og_title":"Hughes | Conectividad satelital y soluciones empresariales","og_description":"Tecnolog\u00eda satelital avanzada y servicios empresariales dise\u00f1ados para asegurar operaci\u00f3n cr\u00edtica, redes estables y continuidad en los entornos m\u00e1s exigentes.","og_url":"https:\/\/www.hughes.com\/mx","og_site_name":"Hughes","article_publisher":"https:\/\/www.facebook.com\/HughesConnects\/","article_modified_time":"2026-02-26T21:03:05+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HughesGlobalOpenGraph.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Hughes | Conectividad satelital y soluciones empresariales","twitter_description":"Tecnolog\u00eda satelital avanzada y servicios empresariales dise\u00f1ados para asegurar operaci\u00f3n cr\u00edtica, redes estables y continuidad en los entornos m\u00e1s exigentes.","twitter_image":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HughesGlobalOpenGraph.jpg","twitter_site":"@HughesConnects","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hughes.com\/mx","url":"https:\/\/www.hughes.com\/mx","name":"Hughes | Conectividad satelital y soluciones empresariales","isPartOf":{"@id":"https:\/\/www.hughes.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hughes.com\/mx#primaryimage"},"image":{"@id":"https:\/\/www.hughes.com\/mx#primaryimage"},"thumbnailUrl":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HughesGlobalOpenGraph.jpg","datePublished":"2025-12-26T09:17:08+00:00","dateModified":"2026-02-26T21:03:05+00:00","description":"Tecnolog\u00eda satelital avanzada y servicios empresariales dise\u00f1ados para asegurar operaci\u00f3n cr\u00edtica, redes estables y continuidad en los entornos m\u00e1s exigentes.","breadcrumb":{"@id":"https:\/\/www.hughes.com\/mx#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hughes.com\/mx"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.hughes.com\/mx#primaryimage","url":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HughesGlobalOpenGraph.jpg","contentUrl":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HughesGlobalOpenGraph.jpg","width":1200,"height":630,"caption":"Hughes Global"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hughes.com\/mx#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hughes.com\/mx"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/www.hughes.com\/mx\/#website","url":"https:\/\/www.hughes.com\/mx\/","name":"Hughes","description":"","publisher":{"@id":"https:\/\/www.hughes.com\/mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hughes.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.hughes.com\/mx\/#organization","name":"Hughes","url":"https:\/\/www.hughes.com\/mx\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.hughes.com\/mx\/#\/schema\/logo\/image\/","url":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HughesEchoStar_Logo.png","contentUrl":"https:\/\/www.hughes.com\/wp-content\/uploads\/2026\/02\/HughesEchoStar_Logo.png","width":593,"height":213,"caption":"Hughes"},"image":{"@id":"https:\/\/www.hughes.com\/mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HughesConnects\/","https:\/\/x.com\/HughesConnects","https:\/\/www.youtube.com\/user\/HughesTV\/videos","https:\/\/www.linkedin.com\/company\/3569\/admin\/dashboard\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hughes.com\/mx\/wp-json\/wp\/v2\/pages\/34397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hughes.com\/mx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hughes.com\/mx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hughes.com\/mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hughes.com\/mx\/wp-json\/wp\/v2\/comments?post=34397"}],"version-history":[{"count":0,"href":"https:\/\/www.hughes.com\/mx\/wp-json\/wp\/v2\/pages\/34397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hughes.com\/mx\/wp-json\/wp\/v2\/media\/30997"}],"wp:attachment":[{"href":"https:\/\/www.hughes.com\/mx\/wp-json\/wp\/v2\/media?parent=34397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}